{"id":2908,"date":"2023-08-15T21:30:48","date_gmt":"2023-08-15T21:30:48","guid":{"rendered":"https:\/\/ddentalworldtourism.com\/faccette-dentali\/"},"modified":"2024-03-03T16:46:40","modified_gmt":"2024-03-03T16:46:40","slug":"faccette-dentali","status":"publish","type":"page","link":"https:\/\/ddentalworldtourism.com\/it\/faccette-dentali\/","title":{"rendered":"Faccette Dentali"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2908\" class=\"elementor elementor-2908 elementor-468\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a771db elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7a771db\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-127e497\" data-id=\"127e497\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c321bab elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c321bab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cce651c\" data-id=\"cce651c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-355724d elementor-widget elementor-widget-heading\" data-id=\"355724d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HOLLYWOOD SMILE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8cd5e9 elementor-widget elementor-widget-image\" data-id=\"b8cd5e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"705\" height=\"150\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-438171342e3e449810f46b95402ce3118eab55268c032ff77ab981c6a8fd4a98_1b936b409c1d6987.png\" class=\"attachment-full size-full wp-image-846\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-438171342e3e449810f46b95402ce3118eab55268c032ff77ab981c6a8fd4a98_1b936b409c1d6987.png 705w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-438171342e3e449810f46b95402ce3118eab55268c032ff77ab981c6a8fd4a98_1b936b409c1d6987-300x64.png 300w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bc58b1 elementor-widget elementor-widget-heading\" data-id=\"6bc58b1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">[currency value=\"2400\"]<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce8e883 elementor-widget elementor-widget-text-editor\" data-id=\"ce8e883\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>10\/14 giorni<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2cca6d elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f2cca6d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PRENOTA ORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3676473 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3676473\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Consulto <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anamnesi e X-Ray <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10 veneers<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Digital Smile Design<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mock-Up (denti provvisori, simulazione dei denti definitivi)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Transfer aeroporto <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cb73001\" data-id=\"cb73001\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60a9af7 elementor-widget elementor-widget-image\" data-id=\"60a9af7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/8.jpg\" class=\"attachment-full size-full wp-image-379\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/8.jpg 720w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/8-300x200.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f154c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f154c9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e82da9\" data-id=\"5e82da9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b1bf97 elementor-widget elementor-widget-spacer\" data-id=\"5b1bf97\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a9bb98 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4a9bb98\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55d4252\" data-id=\"55d4252\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-feb133c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"feb133c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cca723e\" data-id=\"cca723e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62397ea elementor-widget elementor-widget-heading\" data-id=\"62397ea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SOFT SMILE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d0c516 elementor-widget elementor-widget-image\" data-id=\"1d0c516\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"514\" height=\"218\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-c649c60786cba9301c22d42907b0345e20c98991845d12a16f510792cd587a50_c5ef68859f54c8e5.png\" class=\"attachment-full size-full wp-image-850\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-c649c60786cba9301c22d42907b0345e20c98991845d12a16f510792cd587a50_c5ef68859f54c8e5.png 514w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-c649c60786cba9301c22d42907b0345e20c98991845d12a16f510792cd587a50_c5ef68859f54c8e5-300x127.png 300w\" sizes=\"(max-width: 514px) 100vw, 514px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-755c201 elementor-widget elementor-widget-heading\" data-id=\"755c201\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">[currency value=\"1620\"]<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-821cfbd elementor-widget elementor-widget-text-editor\" data-id=\"821cfbd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>10\/14 giorni<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bec6761 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"bec6761\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PRENOTA ORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-464f1f0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"464f1f0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Consulto <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anamnesi e X-Ray <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10 veneers<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Digital Smile Design<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mock-Up (denti provvisori, simulazione dei denti definitivi)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Transfer aeroporto <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-06fa2b2\" data-id=\"06fa2b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7026a4c elementor-widget elementor-widget-image\" data-id=\"7026a4c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"600\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete6.png\" class=\"attachment-full size-full wp-image-1013\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete6.png 764w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete6-300x236.png 300w\" sizes=\"(max-width: 764px) 100vw, 764px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e23bd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e23bd5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47e0c7b\" data-id=\"47e0c7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44ae327 section-align-center section-size-default subtitle-style-default elementor-widget elementor-widget-section-heading\" data-id=\"44ae327\" data-element_type=\"widget\" data-widget_type=\"section-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"section-heading headingstyle-default\"><div class=\"section-title-wrapper\"><h2 class=\"entry-title section-title\">Faccette Dentali<br> Trasforma il Tuo Sorriso con Eleganza<\/h2><\/div><div class=\"section-description clearfix\"><div class=\"section-description-inner\"><p><span style=\"font-weight: 400;\">Benvenuti nel mondo delle Faccette e scopri il segreto di un sorriso perfetto e radiante attraverso le faccette dentali. Scopri come questa soluzione innovativa possa trasformare l'aspetto dei tuoi denti e ripristinare la fiducia nel tuo sorriso.<\/span><\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c87b61 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"8c87b61\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbeda1c\" data-id=\"fbeda1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b9c644 swiper-height-style-custom elementor-widget elementor-widget-image-reel\" data-id=\"2b9c644\" data-element_type=\"widget\" data-widget_type=\"image-reel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"multislider-container-outer reel-slider\"><div id=\"2908-6a52c5f018d42\" class=\"swiper-container swiper-init swiper-slides-overlay shortcode-multislider-container swiperpagination-yes swiper-columns-0 multi-column-slider desktopoffset-yes mobileoffset-yes\" data-slidestyle=\"slide\" data-slidetotal=\"5\" data-swiperpagination=\"yes\" data-autoplay=\"400\" data-columns=\"0\" data-desktopoffset=\"yes\" data-mobileoffset=\"yes\" data-id=\"2908-6a52c5f018d42\">\n\t    <div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" class=\"image-reel-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/343492353_541259051416433_424997570381651956_n-1.jpg\" alt=\"\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" class=\"image-reel-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/385508596_179512505188628_8387187375933934700_n-1.jpg\" alt=\"\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" class=\"image-reel-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/386061987_179512415188637_7791541213244890052_n-1.jpg\" alt=\"\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" class=\"image-reel-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/386067342_179512575188621_7559999315265178386_n-1.jpg\" alt=\"\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" class=\"image-reel-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/385877195_179512391855306_8388944876945631700_n-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-pagination\"><\/div><div class=\"swiper-button-prev\"><i class=\"feather-icon-arrow-left\"><\/i><\/div><div class=\"swiper-button-next\"><i class=\"feather-icon-arrow-right\"><\/i><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d93c7b elementor-widget elementor-widget-image\" data-id=\"5d93c7b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"638\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2.jpg\" class=\"attachment-full size-full wp-image-735\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2.jpg 1920w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2-300x100.jpg 300w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2-1024x340.jpg 1024w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2-768x255.jpg 768w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2-1536x510.jpg 1536w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2-1400x465.jpg 1400w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/fatete2-800x266.jpg 800w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab6c2d elementor-widget elementor-widget-text-editor\" data-id=\"7ab6c2d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><b>Cos&#8217;\u00e8 una Faccetta Dentale?\u00a0<\/b><\/span><\/p>\n<p><span style=\"font-weight: 400; color: #ffffff;\">Le faccette dentali sono sottili coperture personalizzate, solitamente realizzate in porcellana o materiali compositi di alta qualit\u00e0, che vengono applicate sulla superficie esterna dei denti per migliorare l&#8217;aspetto estetico.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd4413 elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"5dd4413\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30f552b\" data-id=\"30f552b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19594e8 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"19594e8\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/27-1.jpg\" alt=\"27.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/28-1.jpg\" alt=\"28.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/14-1.jpg\" alt=\"14.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/17-1.jpg\" alt=\"17.jpg\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05e1fad elementor-widget elementor-widget-image\" data-id=\"05e1fad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel.jpg\" class=\"attachment-full size-full wp-image-2667\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel.jpg 1080w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel-300x300.jpg 300w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel-1024x1024.jpg 1024w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel-150x150.jpg 150w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel-768x768.jpg 768w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel-770x770.jpg 770w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel-160x160.jpg 160w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/treatments-tel-800x800.jpg 800w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9503754 elementor-widget elementor-widget-text-editor\" data-id=\"9503754\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<b>Cos&#8217;\u00e8 una Faccetta Dentale?\u00a0<\/b>\r\n\r\n<span style=\"font-weight: 400;\">Le faccette dentali sono sottili coperture personalizzate, solitamente realizzate in porcellana o materiali compositi di alta qualit\u00e0, che vengono applicate sulla superficie esterna dei denti per migliorare l&#8217;aspetto estetico.<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-caf9d52 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"caf9d52\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e83b6e\" data-id=\"7e83b6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7bf4c0 elementor-widget elementor-widget-heading\" data-id=\"b7bf4c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vantaggi delle Faccette Dentali <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b74ae0f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b74ae0f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-701010e\" data-id=\"701010e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e177f84 eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"e177f84\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content eael-flip-box-hover\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon fas fa-check-circle\"><\/i>                                                                                    <\/div>\n                                    <p class=\"eael-elements-flip-box-heading\">Aspetto Naturale<\/p>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p>\u00a0Le faccette ripristinano un aspetto naturale e radiante ai denti, indipendentemente dalle imperfezioni precedenti.<\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n        <script>\n            jQuery(document).ready(function( $ ) {\n                $(\".eael-flip-box-click\").off('click').on( 'click', function( event ) {\n                    $(this).toggleClass( '--active' );\n                });\n            });\n        <\/script>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-13e8c10\" data-id=\"13e8c10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c19c126 eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"c19c126\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content eael-flip-box-hover\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon fas fa-check-circle\"><\/i>                                                                                    <\/div>\n                                    <p class=\"eael-elements-flip-box-heading\">Durata Resiliente<\/p>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p>I materiali moderni garantiscono resistenza e durata nel lungo termine. <\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n        <script>\n            jQuery(document).ready(function( $ ) {\n                $(\".eael-flip-box-click\").off('click').on( 'click', function( event ) {\n                    $(this).toggleClass( '--active' );\n                });\n            });\n        <\/script>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4742112\" data-id=\"4742112\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4df3379 eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"4df3379\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content eael-flip-box-hover\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon fas fa-check-circle\"><\/i>                                                                                    <\/div>\n                                    <p class=\"eael-elements-flip-box-heading\">Correzione delle Imperfezioni<\/p>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p>Macchie, crepe, decolorazioni &#8211; le faccette coprono una variet\u00e0 di problemi estetici. <\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n        <script>\n            jQuery(document).ready(function( $ ) {\n                $(\".eael-flip-box-click\").off('click').on( 'click', function( event ) {\n                    $(this).toggleClass( '--active' );\n                });\n            });\n        <\/script>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-00af641\" data-id=\"00af641\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-375222f eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"375222f\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content eael-flip-box-hover\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon fas fa-check-circle\"><\/i>                                                                                    <\/div>\n                                    <p class=\"eael-elements-flip-box-heading\">Aumento della Fiducia<\/p>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p>Con un sorriso nuovo e accattivante, sperimenti un aumento dell&#8217;autostima. <\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n        <script>\n            jQuery(document).ready(function( $ ) {\n                $(\".eael-flip-box-click\").off('click').on( 'click', function( event ) {\n                    $(this).toggleClass( '--active' );\n                });\n            });\n        <\/script>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e7934da\" data-id=\"e7934da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d12aab eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"8d12aab\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content eael-flip-box-hover\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon fas fa-check-circle\"><\/i>                                                                                    <\/div>\n                                    <p class=\"eael-elements-flip-box-heading\">Processo Indolore<\/p>                                    <div class=\"eael-elements-flip-box-content\">\n\t                                                                        <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                                                            <div class=\"eael-elements-flip-box-content\">\n                                        <p>L&#8217;applicazione delle faccette \u00e8 confortevole e indolore, offrendo risultati rapidi.<\/p>                                    <\/div>\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n        <script>\n            jQuery(document).ready(function( $ ) {\n                $(\".eael-flip-box-click\").off('click').on( 'click', function( event ) {\n                    $(this).toggleClass( '--active' );\n                });\n            });\n        <\/script>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2303e41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2303e41\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06df79c\" data-id=\"06df79c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bdf536 elementor-widget elementor-widget-heading\" data-id=\"1bdf536\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fasi del Trattamento con Faccette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca40955 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ca40955\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Consulenza e Piano:<\/b> Discutiamo dei tuoi obiettivi e creiamo un piano personalizzato per il trattamento con faccette. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Preparazione dei Denti:<\/b> Viene rimossa una piccola quantit\u00e0 di smalto per fare spazio alle faccette. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Impressione Dettagliata:<\/b> Viene presa un'accurata impressione per creare faccette adattate alla forma unica dei tuoi denti. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Applicazione Temporanea:<\/b> Ricevi faccette temporanee per vedere come appaiono e si sentono. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Applicazione delle Faccette Definitive:<\/b> Le faccette personalizzate vengono attaccate permanentemente per un sorriso nuovo e brillante.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bac1d8a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bac1d8a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cedb0c3\" data-id=\"cedb0c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37a9867 elementor-widget elementor-widget-heading\" data-id=\"37a9867\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cura delle Tue Faccette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f214484 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f214484\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf73f1b\" data-id=\"cf73f1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9843fdf elementor-widget elementor-widget-image\" data-id=\"9843fdf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"500\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/igiena.jpg\" class=\"attachment-full size-full wp-image-1072\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/igiena.jpg 960w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/igiena-300x156.jpg 300w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/igiena-768x400.jpg 768w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/igiena-800x417.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-583ea76\" data-id=\"583ea76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b3a31a elementor-widget elementor-widget-text-editor\" data-id=\"0b3a31a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Igiene Orale Approfondita<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Continua a lavare i denti e ad usare il filo interdentale regolarmente per mantenere una salute orale ottimale. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b7d028 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3b7d028\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-71a688f\" data-id=\"71a688f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-472edd5 elementor-widget elementor-widget-text-editor\" data-id=\"472edd5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Visite di Controllo Regolari<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Le visite dal dentista per controlli periodici aiutano a mantenere la salute delle faccette.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9587abb\" data-id=\"9587abb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f6bd06 elementor-widget elementor-widget-image\" data-id=\"9f6bd06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"500\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/visit-regular.jpg\" class=\"attachment-full size-full wp-image-1073\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/visit-regular.jpg 960w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/visit-regular-300x156.jpg 300w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/visit-regular-768x400.jpg 768w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/visit-regular-800x417.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b2da9b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3b2da9b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f1fd523\" data-id=\"f1fd523\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ff1d43 elementor-widget elementor-widget-image\" data-id=\"4ff1d43\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"500\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/pencil.jpg\" class=\"attachment-full size-full wp-image-1086\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/pencil.jpg 960w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/pencil-300x156.jpg 300w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/pencil-768x400.jpg 768w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/pencil-800x417.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-494a7ef\" data-id=\"494a7ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a52683a elementor-widget elementor-widget-text-editor\" data-id=\"a52683a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Evitare Stress<\/b><\/h3>\r\n<span style=\"font-weight: 400;\">Evita abitudini che potrebbero esercitare pressione eccessiva sui denti, come rosicchiare le unghie o masticare penne.<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16fc0a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16fc0a0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-855db6d\" data-id=\"855db6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47334da elementor-widget elementor-widget-text-editor\" data-id=\"47334da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"font-weight: 400; color: #ffffff;\">Contattaci per un Nuovo Sorriso <\/span><\/h3><p><span style=\"font-weight: 400; color: #ffffff;\">Trasforma il tuo sorriso con l&#8217;aiuto delle faccette dentali e intraprendi un viaggio verso un sorriso perfetto e fiducioso. Contattaci oggi stesso per una consulenza personalizzata e scopri la bellezza di un sorriso impeccabile!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e314f84\" data-id=\"e314f84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96cad26 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"96cad26\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulto Gratis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7267dd6 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"7267dd6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6b76a0\" data-id=\"b6b76a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3199ee elementor-widget elementor-widget-heading\" data-id=\"b3199ee\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visualizza le altre offerte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d69bc3 elementor-widget elementor-widget-text-editor\" data-id=\"1d69bc3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Scegli la tua valuta [currency-switch]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-46ac7bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46ac7bd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-8b03e5a\" data-id=\"8b03e5a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b53464f elementor-widget elementor-widget-heading\" data-id=\"b53464f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALL ON 4 <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-667458b elementor-widget elementor-widget-image\" data-id=\"667458b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"439\" height=\"278\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-35c3e4df5f22017c7e8f61de70b676989a86632a699582f8f8831d62d2743ad1_866257ddd62e794a.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-849\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-35c3e4df5f22017c7e8f61de70b676989a86632a699582f8f8831d62d2743ad1_866257ddd62e794a.png 439w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-35c3e4df5f22017c7e8f61de70b676989a86632a699582f8f8831d62d2743ad1_866257ddd62e794a-300x190.png 300w\" sizes=\"(max-width: 439px) 100vw, 439px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5e0fa4 elementor-widget elementor-widget-heading\" data-id=\"f5e0fa4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">[currency value=\"2130\"]<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ab41f9 elementor-widget elementor-widget-text-editor\" data-id=\"5ab41f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per arcata<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ffcb24 elementor-widget elementor-widget-text-editor\" data-id=\"8ffcb24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4 giorni<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97a1b08 elementor-widget elementor-widget-text-editor\" data-id=\"97a1b08\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul style=\"list-style-position: outside;\"><li>Consulto<\/li><li>Analisi e X-Ray<\/li><li>Farmaci<\/li><li>Alloggio\u00a0<\/li><li>Protesi fissa in PMMA<\/li><li>Transfer aeroporto<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b7fcd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"73b7fcd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-5198956\" data-id=\"5198956\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52269ce elementor-widget elementor-widget-heading\" data-id=\"52269ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALL ON 6 <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4569448 elementor-widget elementor-widget-image\" data-id=\"4569448\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"437\" height=\"300\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-7bc92ab366a2a3d27fe76682f878c0e99e47d31308a2d87ea364b389c68bd956_ac0aaeff67b73fc1.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-848\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-7bc92ab366a2a3d27fe76682f878c0e99e47d31308a2d87ea364b389c68bd956_ac0aaeff67b73fc1.png 437w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-7bc92ab366a2a3d27fe76682f878c0e99e47d31308a2d87ea364b389c68bd956_ac0aaeff67b73fc1-300x206.png 300w\" sizes=\"(max-width: 437px) 100vw, 437px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ad9a51 elementor-widget elementor-widget-heading\" data-id=\"9ad9a51\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">[currency value=\"2660\"]<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2d91ad elementor-widget elementor-widget-text-editor\" data-id=\"b2d91ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per arcata<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9ec118 elementor-widget elementor-widget-text-editor\" data-id=\"e9ec118\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4 giorni<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d8fb46 elementor-widget elementor-widget-text-editor\" data-id=\"6d8fb46\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul style=\"list-style-position: outside;\"><li>Consulto<\/li><li>Analisi e X-Ray<\/li><li>Farmaci<\/li><li>Alloggio<\/li><li>Protesi fissa in PMMA<\/li><li>Transfer aeroporto<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da0848b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"da0848b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-c6725ae\" data-id=\"c6725ae\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1a9515 elementor-widget elementor-widget-heading\" data-id=\"b1a9515\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OLA <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ed7b4f elementor-widget elementor-widget-image\" data-id=\"0ed7b4f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"439\" height=\"278\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/09\/0-02-05-5a7b1c6bb01a06ad6ef4fcf6ed870957d639a6a4d3fb73579f0423009cd2c581_70d159b92a3950d6.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-2288\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/09\/0-02-05-5a7b1c6bb01a06ad6ef4fcf6ed870957d639a6a4d3fb73579f0423009cd2c581_70d159b92a3950d6.png 439w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/09\/0-02-05-5a7b1c6bb01a06ad6ef4fcf6ed870957d639a6a4d3fb73579f0423009cd2c581_70d159b92a3950d6-300x190.png 300w\" sizes=\"(max-width: 439px) 100vw, 439px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91cd405 elementor-widget elementor-widget-heading\" data-id=\"91cd405\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">[currency value=\"700\"]-[currency value=\"900\"]<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b22a6c5 elementor-widget elementor-widget-text-editor\" data-id=\"b22a6c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per arcata<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-820d2b4 elementor-widget elementor-widget-text-editor\" data-id=\"820d2b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul style=\"list-style-position: outside;\"><li>Consulto<\/li><li>Anamnesi e X-Ray<\/li><li>OLA trattamento completo<\/li><li>Igiene professionale<\/li><li>Sbiancamento<\/li><li>Transfer aeroporto<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a186f12 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a186f12\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-1c590e7\" data-id=\"1c590e7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f98a468 elementor-widget elementor-widget-heading\" data-id=\"f98a468\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SOFT SMILE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e407580 elementor-widget elementor-widget-image\" data-id=\"e407580\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"514\" height=\"218\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-c649c60786cba9301c22d42907b0345e20c98991845d12a16f510792cd587a50_c5ef68859f54c8e5.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-850\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-c649c60786cba9301c22d42907b0345e20c98991845d12a16f510792cd587a50_c5ef68859f54c8e5.png 514w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-c649c60786cba9301c22d42907b0345e20c98991845d12a16f510792cd587a50_c5ef68859f54c8e5-300x127.png 300w\" sizes=\"(max-width: 514px) 100vw, 514px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b947634 elementor-widget elementor-widget-heading\" data-id=\"b947634\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">[currency value=\"1620\"]<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-882a59a elementor-widget elementor-widget-text-editor\" data-id=\"882a59a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>10\/14 giorni<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2810be elementor-widget elementor-widget-text-editor\" data-id=\"c2810be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul style=\"list-style-position: outside;\"><li>Consulto<\/li><li>Anamnesi e X-Ray<\/li><li>6 veneers<\/li><li>Digital Smile Designs<\/li><li>Mock-Up (denti provvisori, simulazione dei denti definitivi)<\/li><li>Transfer aeroporto<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d66f9a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9d66f9a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-1e24428\" data-id=\"1e24428\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f7fc1f elementor-widget elementor-widget-heading\" data-id=\"7f7fc1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HOLLYWOOD SMILE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93ba9de elementor-widget elementor-widget-image\" data-id=\"93ba9de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"150\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-438171342e3e449810f46b95402ce3118eab55268c032ff77ab981c6a8fd4a98_1b936b409c1d6987.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-846\" alt=\"\" srcset=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-438171342e3e449810f46b95402ce3118eab55268c032ff77ab981c6a8fd4a98_1b936b409c1d6987.png 705w, https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/08\/0-02-05-438171342e3e449810f46b95402ce3118eab55268c032ff77ab981c6a8fd4a98_1b936b409c1d6987-300x64.png 300w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8597a4 elementor-widget elementor-widget-heading\" data-id=\"c8597a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">[currency value=\"2400\"]<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36a700d elementor-widget elementor-widget-text-editor\" data-id=\"36a700d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>10\/14 giorni<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7326871 elementor-widget elementor-widget-text-editor\" data-id=\"7326871\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul style=\"list-style-position: outside;\"><li>Consulto<\/li><li>Anamnesi e X-Ray<\/li><li>10 veneers<\/li><li>Digital Smile Designs<\/li><li>Mock-Up (denti provvisori, simulazione dei denti definitivi)<\/li><li>Transfer aeroporto<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39493af elementor-align-center elementor-widget elementor-widget-button\" data-id=\"39493af\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#popmake-3173\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-70e6547 elementor-widget elementor-widget-heading\" data-id=\"70e6547\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scegli un trattamento dentale di qualit\u00e0 all'estero - La tua soluzione per il turismo dentale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd29fb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd29fb7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c17412\" data-id=\"9c17412\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec8737 elementor-widget elementor-widget-heading\" data-id=\"eec8737\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NOI ORGANIZZIAMO TUTTO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a5278ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5278ba\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3f2d8ee\" data-id=\"3f2d8ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63bbf9f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"63bbf9f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/2_1.jpg\" class=\"attachment-full size-full wp-image-5900\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Airport Transfer<\/h3><p class=\"elementor-image-box-description\">La tua sicurezza \u00e8 la nostra priorit\u00e0. I tuoi viaggi e le tue esperienze di trattamento sono al sicuro con noi. Ti accogliamo in aeroporto e ti accompagniamo.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6fe2166\" data-id=\"6fe2166\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a39bfd5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a39bfd5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/3_1.jpg\" class=\"attachment-full size-full wp-image-5904\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Alloggio<\/h3><p class=\"elementor-image-box-description\">La nostra clinica offre alloggio nelle immediate vicinanze per la tua comodit\u00e0.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cfdb220\" data-id=\"cfdb220\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a73640 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6a73640\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/10\/1_1.jpg\" class=\"attachment-full size-full wp-image-5908\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Follow Up<\/h3><p class=\"elementor-image-box-description\">\u00c8 nostro dovere monitorare il tuo piano di cura prima e dopo la tua visita in clinica.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>HOLLYWOOD SMILE [currency value=&#8221;2400&#8243;] 10\/14 giorni PRENOTA ORA Consulto Anamnesi e X-Ray 10 veneers Digital Smile Design Mock-Up (denti provvisori, simulazione dei denti definitivi) Transfer aeroporto SOFT SMILE [currency value=&#8221;1620&#8243;] 10\/14 giorni PRENOTA ORA Consulto Anamnesi e X-Ray 10 veneers Digital Smile Design Mock-Up (denti provvisori, simulazione dei denti definitivi) Transfer aeroporto Faccette Dentali Trasforma il Tuo Sorriso con Eleganza Benvenuti nel mondo delle Faccette e scopri il segreto di un sorriso perfetto e radiante attraverso le faccette dentali. Scopri [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2908","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"ddentalworldtourism.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L&#039;immagine in evidenza dovrebbe essere di almeno 200 x 200 pixel per essere ripresa da Facebook e altri siti di social media.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"faccette-dentali","permalinkFormat":"https:\/\/ddentalworldtourism.com\/it\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/ddentalworldtourism.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nome utente","primaryTerm":0,"authorName":"info@ddentalworldtourism.com","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/ddentalworldtourism.com\/it\/","objectID":2908,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Icona di riproduzione","url":"https:\/\/ddentalworldtourism.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/ddentalw\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icona GIF","url":"https:\/\/ddentalworldtourism.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/ddentalw\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/ddentalworldtourism.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fddentalworldtourism.com%2Fit%2F&r=https%3A%2F%2Fddentalworldtourism.com%2Fit%2Fwp-json%2Fwp%2Fv2%2Fpages%2F2908%3Fnonce%3D02ab6cde2f","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/ddentalworldtourism.com\/wp-content\/uploads\/2023\/09\/cropped-0-02-05-44e16f0abd4f1d68e041f42097f58f7ec323b7ddd45b08928461c02cedd19b1c_b2edf042214ab9c-32x32.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Aggiorna","trendsPreviewImage":"https:\/\/ddentalworldtourism.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/pages\/2908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/comments?post=2908"}],"version-history":[{"count":70,"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/pages\/2908\/revisions"}],"predecessor-version":[{"id":8319,"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/pages\/2908\/revisions\/8319"}],"wp:attachment":[{"href":"https:\/\/ddentalworldtourism.com\/it\/wp-json\/wp\/v2\/media?parent=2908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}